{"id":14730,"date":"2026-06-28T22:45:14","date_gmt":"2026-06-28T22:45:14","guid":{"rendered":"https:\/\/www.noticias247.com.co\/news\/?p=14730"},"modified":"2026-06-30T22:53:51","modified_gmt":"2026-06-30T22:53:51","slug":"la-magdalena-ya-tiene-su-gran-polideportivo-con-la-entrega-de-ring-de-boxeo-y-estadio-de-beisbol-alcalde-char-completa-esta-unidad-deportiva","status":"publish","type":"post","link":"https:\/\/www.noticias247.com.co\/news\/2026\/06\/28\/la-magdalena-ya-tiene-su-gran-polideportivo-con-la-entrega-de-ring-de-boxeo-y-estadio-de-beisbol-alcalde-char-completa-esta-unidad-deportiva\/","title":{"rendered":"La Magdalena ya tiene su gran polideportivo! Con la entrega de ring de boxeo y estadio de b\u00e9isbol, alcalde Char completa esta unidad deportiva"},"content":{"rendered":"\n<p><em>El espacio integra escenarios para b\u00e9isbol, boxeo, f\u00fatbol, patinaje y recreaci\u00f3n, consolid\u00e1ndose como un referente para el deporte en toda la ciudad.<\/em><\/p>\n\n\n\n<p>\u00a1La&nbsp;<strong>transformaci\u00f3n del polideportivo La Magdalena<\/strong>&nbsp;ya es una realidad! El alcalde Alejandro Char puso oficialmente al servicio de la comunidad el nuevo estadio de b\u00e9isbol y el ring de boxeo, obras que completan la recuperaci\u00f3n de este emblem\u00e1tico complejo deportivo del suroriente de Barranquilla.<\/p>\n\n\n\n<p>El alcalde Char expres\u00f3: \u201c\u00a1La Magdalena ya tiene su gran polideportivo! Pista de patinaje, canchas de f\u00fatbol y ahora un moderno&nbsp;<strong>escenario para el boxeo<\/strong>, adem\u00e1s de un tremendo&nbsp;<strong>estadio de b\u00e9isbol<\/strong>. Con esta entrega completamos este gran complejo deportivo, como lo so\u00f1\u00f3 su gente. Una inversi\u00f3n de m\u00e1s de $28.290 millones para brindarles a nuestros ni\u00f1os y j\u00f3venes escenarios de primer nivel, donde puedan entrenar, competir y cumplir sus sue\u00f1os. Hoy nuestro Suroriente tiene un polideportivo a la altura de los grandes talentos de nuestra ciudad. Aqu\u00ed se formar\u00e1n nuestros semilleros deportivos y de aqu\u00ed saldr\u00e1n los pr\u00f3ximos campeones de Barranquilla y de Colombia!\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-x wp-block-embed-x\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u00a1La Magdalena ya tiene su gran polideportivo! Pista de patinaje, canchas de f\u00fatbol y ahora un moderno escenario para el boxeo, adem\u00e1s de un tremendo estadio de b\u00e9isbol. \u26be\ud83e\udd4a<br><br>Con esta entrega completamos este gran complejo deportivo, como lo so\u00f1\u00f3 su gente. Una inversi\u00f3n de m\u00e1s de\u2026 <a href=\"https:\/\/t.co\/kvkhqeIYDO\">pic.twitter.com\/kvkhqeIYDO<\/a><\/p>&mdash; Alejandro Char (@AlejandroChar) <a href=\"https:\/\/x.com\/AlejandroChar\/status\/2071303865643966888?ref_src=twsrc%5Etfw\">June 28, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Esta nueva entrega, junto con el gimnasio especializado y el m\u00f3dulo de servicios, &nbsp;permite que la comunidad disfrute espacios modernos, seguros y dignos donde ni\u00f1os, j\u00f3venes y deportistas podr\u00e1n entrenar, competir y construir proyectos de vida alrededor del deporte, en un lugar que hoy resurge y se convierte en motivo de orgullo para sus habitantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Centro de alto rendimiento<\/strong><\/h2>\n\n\n\n<p>Con esta transformaci\u00f3n, el polideportivo La Magdalena se consolida como un gran complejo para el deporte y la recreaci\u00f3n, al integrar escenarios para b\u00e9isbol, boxeo, f\u00fatbol, patinaje, zonas de entrenamiento, espacios para la actividad f\u00edsica y \u00e1reas de encuentro comunitario, fortaleciendo la oferta deportiva del Distrito y ampliando las oportunidades para miles de barranquilleros.<\/p>\n\n\n\n<p>En ese sentido, el renovado estadio de b\u00e9isbol fue concebido para impulsar la formaci\u00f3n de las nuevas generaciones de peloteros, mientras que el complejo de boxeo ofrece un escenario adecuado para el entrenamiento y desarrollo de quienes encuentran en esta disciplina una oportunidad de crecimiento personal y deportivo.<\/p>\n\n\n\n<p>Al respecto, &nbsp;el alcalde Char destac\u00f3 que: \u201cM\u00e1s all\u00e1 de un parque, un escenario deportivo, esto es un centro de alto rendimiento, aqu\u00ed se preparan los semilleros para la gran carpa y el pelao que viene aqu\u00ed, que juega aqu\u00ed, lo sientan despu\u00e9s en el Yankee Stadium y no le da pena ni le da miedo porque se hizo en los mismos espacios que tienen ellos all\u00e1: misma grama de bermuda, la misma arcilla, entonces nuestros pelaos se empoderan. Barranquilla es la capital del deporte en Colombia\u201d.<\/p>\n\n\n\n<p>El mandatario agreg\u00f3 que el talento de los j\u00f3venes de Barranquilla y la regi\u00f3n Caribe se forjar\u00e1n en escenarios como este polideportivo. \u201cTenemos que hacer estos espacios para que el pelao se enamore de esto, porque esto tambi\u00e9n es una oportunidad de vida para \u00e9l y para su familia; el talento que &nbsp;hay aqu\u00ed en Barranquilla, que hay aqu\u00ed en el Caribe es \u00fanico, pero hay que darle las horas, los instructores, que no le falte el guante, el uniforme, los&nbsp;<em>coaches<\/em>&nbsp;aqu\u00ed motiv\u00e1ndolos, y nosotros como ciudad haciendo esto, porque esto sin grama, sin luces no funciona, entonces estamos todos juntos aqu\u00ed para que nuestros pelados tengan sue\u00f1os que se pueden convertir en realidad\u201d.<\/p>\n\n\n\n<p>La recuperaci\u00f3n de estos espacios tambi\u00e9n fortalece el tejido social del sector. Al brindar infraestructura deportiva de calidad, la Administraci\u00f3n distrital promueve entornos seguros para el aprovechamiento del tiempo libre, fomenta h\u00e1bitos de vida saludable y crea escenarios donde las familias pueden reunirse alrededor del deporte y la recreaci\u00f3n.<\/p>\n\n\n\n<p>Con la puesta en servicio de este polideportivo, Barranquilla contin\u00faa consolidando una infraestructura deportiva de primer nivel, pensada no solo para formar atletas y albergar competencias, sino tambi\u00e9n para seguir transformando barrios, generar oportunidades para la juventud y fortalecer la convivencia en las comunidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El espacio integra escenarios para b\u00e9isbol, boxeo, f\u00fatbol, patinaje y recreaci\u00f3n, consolid\u00e1ndose como un referente para el deporte en toda la ciudad. \u00a1La&nbsp;transformaci\u00f3n del polideportivo La Magdalena&nbsp;ya es una realidad!&hellip; <\/p>\n","protected":false},"author":1,"featured_media":14732,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-14730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barranquilla"],"blog_post_layout_featured_media_urls":{"thumbnail":["https:\/\/www.noticias247.com.co\/news\/wp-content\/uploads\/2026\/06\/\u00b4pnodeportivo-150x150.jpg",150,150,true],"full":["https:\/\/www.noticias247.com.co\/news\/wp-content\/uploads\/2026\/06\/\u00b4pnodeportivo.jpg",1017,567,false]},"categories_names":{"7":{"name":"BARRANQUILLA","link":"https:\/\/www.noticias247.com.co\/news\/category\/barranquilla\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/posts\/14730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/comments?post=14730"}],"version-history":[{"count":1,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/posts\/14730\/revisions"}],"predecessor-version":[{"id":14733,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/posts\/14730\/revisions\/14733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/media\/14732"}],"wp:attachment":[{"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/media?parent=14730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/categories?post=14730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/tags?post=14730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}