{"id":14740,"date":"2026-06-27T15:09:00","date_gmt":"2026-06-27T15:09:00","guid":{"rendered":"https:\/\/www.noticias247.com.co\/news\/?p=14740"},"modified":"2026-06-30T23:14:00","modified_gmt":"2026-06-30T23:14:00","slug":"mas-herramientas-para-seguir-dandole-duro-a-los-bandidos-alcalde-char-al-entregar-el-centro-local-de-analisis-criminal-a-la-policia","status":"publish","type":"post","link":"https:\/\/www.noticias247.com.co\/news\/2026\/06\/27\/mas-herramientas-para-seguir-dandole-duro-a-los-bandidos-alcalde-char-al-entregar-el-centro-local-de-analisis-criminal-a-la-policia\/","title":{"rendered":"\u00a1M\u00e1s herramientas para seguir d\u00e1ndole duro a los bandidos!: alcalde Char al entregar el Centro Local de An\u00e1lisis Criminal a la Polic\u00eda"},"content":{"rendered":"\n<p>C<em>on una inversi\u00f3n de m\u00e1s de $2.980 millones, la sala ser\u00e1 el &#8216;coraz\u00f3n&#8217; de la investigaci\u00f3n judicial en la ciudad.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>El alcalde de Barranquilla, Alejandro Char, contin\u00faa fortaleciendo la seguridad de la ciudad y, luego de entregar estaciones, CAI, veh\u00edculos y elementos de comunicaci\u00f3n, pone a disposici\u00f3n de la Polic\u00eda Metropolitana el Centro Local de An\u00e1lisis Criminal.<\/p>\n\n\n\n<p>El mandatario distrital expres\u00f3: \u201c\u00a1M\u00e1s herramientas para seguir d\u00e1ndole duro a los bandidos! Hoy entregamos el&nbsp;<strong>Centro Local de An\u00e1lisis Criminal<\/strong>&nbsp;a la @PoliciaBquilla. Desde este nuevo centro se fortalecer\u00e1 el an\u00e1lisis criminal con inteligencia y tecnolog\u00eda, permiti\u00e9ndole a la Polic\u00eda integrar y analizar informaci\u00f3n, identificar patrones delictivos y fortalecer las investigaciones con datos clave para la judicializaci\u00f3n y la desarticulaci\u00f3n de organizaciones criminales que tanto da\u00f1o le hacen a Barranquilla y al Atl\u00e1ntico. Con una inversi\u00f3n de m\u00e1s de $2.980 millones, seguimos fortaleciendo la seguridad de nuestra ciudad. Ya entregamos CAI, estaciones de Polic\u00eda, veh\u00edculos y equipos de comunicaci\u00f3n; hoy damos un paso m\u00e1s para combatir el crimen. Una herramienta m\u00e1s para que los bandidos no sigan congelados. \u00a1Que los descongelen y paguen por todos sus delitos!\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-x wp-block-embed-x\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u00a1M\u00e1s herramientas para seguir d\u00e1ndole duro a los bandidos! Hoy entregamos el Centro Local de An\u00e1lisis Criminal a la <a href=\"https:\/\/x.com\/PoliciaBquilla?ref_src=twsrc%5Etfw\">@PoliciaBquilla<\/a>.<br><br>Desde este nuevo centro se fortalecer\u00e1 el an\u00e1lisis criminal con inteligencia y tecnolog\u00eda, permiti\u00e9ndole a la Polic\u00eda integrar y analizar\u2026 <a href=\"https:\/\/t.co\/iAf49gp2k1\">pic.twitter.com\/iAf49gp2k1<\/a><\/p>&mdash; Alejandro Char (@AlejandroChar) <a href=\"https:\/\/x.com\/AlejandroChar\/status\/2070930223445799333?ref_src=twsrc%5Etfw\">June 27, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Este centro&nbsp;incluye&nbsp;dotaci\u00f3n tecnol\u00f3gica, y ser\u00e1 de gran importancia para el apoyo a la administraci\u00f3n de justicia, ya que desde ella se realizar\u00e1n diferentes tipos de an\u00e1lisis que permitan impactar las estructuras criminales.<\/p>\n\n\n\n<p>El alcalde Alejandro Char resalt\u00f3 que la ciudad ha venido cumpliendo con su deber de brindar herramientas a la fuerza p\u00fablica: \u201cCon los impuestos de los barranquilleros, la Polic\u00eda Nacional se ha dado cuenta del compromiso que la Alcald\u00eda de Barranquilla tiene con la seguridad y con nuestra Polic\u00eda. Esta sala nos pone a la vanguardia, por los equipos y por su gente. Y entiendo que todos estos muchachos y muchachas est\u00e1n preparados. Toda la informaci\u00f3n que estos muchachos saquen de ac\u00e1, del an\u00e1lisis, de su inteligencia, de su estrategia, es muy importante dentro del proceso de la Administraci\u00f3n Distrital, porque atraemos inversi\u00f3n extranjera, porque se le provee seguridad a los negocios, a la gente. Nosotros s\u00ed creemos que la seguridad le trae prosperidad a la gente\u201d.<\/p>\n\n\n\n<p>El Centro Local de An\u00e1lisis Criminal ser\u00e1 operado por 31 analistas criminales, 16 investigadores criminol\u00f3gicos y dos jefes de l\u00ednea, quienes tendr\u00e1n equipos de c\u00f3mputo de la m\u00e1s alta tecnolog\u00eda.<\/p>\n\n\n\n<p>Char enfatiz\u00f3 que la tarea de la Administraci\u00f3n se est\u00e1 haciendo y que estas herramientas van a potenciar el talento en materia de inteligencia para la seguridad: \u201cEstoy muy orgulloso de hacerles esta inversi\u00f3n y yo s\u00e9 que esta herramienta nos va a dar, y eso, los resultados que yo s\u00e9 que usted y toda su gente nos quiere dar todos los d\u00edas\u201d.<\/p>\n\n\n\n<p>Estos funcionarios policiales tienen la misi\u00f3n, entre otras, de recolectar, analizar y evaluar la informaci\u00f3n judicial de personas y organizaciones delincuenciales, con el prop\u00f3sito de elaborar documentos estrat\u00e9gicos y operacionales, identificando patrones y tendencias delictivas.<\/p>\n\n\n\n<p>Adem\u00e1s, podr\u00e1n integrar la informaci\u00f3n de las especialidades de investigaci\u00f3n criminal e inteligencia de la Polic\u00eda, con el fin de generar documentos estrat\u00e9gicos que permitan apoyar la toma de decisiones de los comandantes de la Polic\u00eda Metropolitana y la Administraci\u00f3n Distrital, que apunten a la reducci\u00f3n de las conductas delictivas.<\/p>\n\n\n\n<p>Tambi\u00e9n, los investigadores y analistas podr\u00e1n analizar los datos para la judicializaci\u00f3n de personas y la desarticulaci\u00f3n de organizaciones criminales.<\/p>\n\n\n\n<p>El Centro Local de An\u00e1lisis Criminal tambi\u00e9n cuenta con una sala de juntas y una sala de crisis, y ser\u00e1 la sede del Grupo de Informaci\u00f3n de la Criminalidad.<\/p>\n\n\n\n<p>El mandatario record\u00f3 que en Barranquilla se ha hecho equipo entre las instituciones competentes para combatir la delincuencia: \u201cEstamos haciendo unos esfuerzos muy grandes. El gobernador Verano y mi persona estamos disponiendo de 600.000 millones de pesos para la seguridad. Era plata que quiz\u00e1s pudi\u00e9ramos estar invirtiendo en otros frentes, pero entendemos que la seguridad es trascendental para la econom\u00eda de todos los que viven ac\u00e1 y yo s\u00e9 que esa seguridad no la pueden dar ustedes solos\u201d.<\/p>\n\n\n\n<p>Con la entrega de estaciones, CAI y veh\u00edculos se fortalece la seguridad ciudadana y la vigilancia en los diferentes sectores, mientras que con este nuevo centro&nbsp;la&nbsp;<a href=\"https:\/\/barranquilla.gov.co\/secgobierno\">Administraci\u00f3n Distrital<\/a>&nbsp;busca darle m\u00e1s herramientas a la Polic\u00eda para el desarrollo de estrategias basadas en la investigaci\u00f3n y el an\u00e1lisis criminal, fundamentales para la afectaci\u00f3n a estructuras delictivas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una inversi\u00f3n de m\u00e1s de $2.980 millones, la sala ser\u00e1 el &#8216;coraz\u00f3n&#8217; de la investigaci\u00f3n judicial en la ciudad. El alcalde de Barranquilla, Alejandro Char, contin\u00faa fortaleciendo la seguridad&hellip; <\/p>\n","protected":false},"author":1,"featured_media":14741,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-14740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barranquilla"],"blog_post_layout_featured_media_urls":{"thumbnail":["https:\/\/www.noticias247.com.co\/news\/wp-content\/uploads\/2026\/06\/alcalde-y-seguridad-150x150.jpg",150,150,true],"full":["https:\/\/www.noticias247.com.co\/news\/wp-content\/uploads\/2026\/06\/alcalde-y-seguridad.jpg",1171,632,false]},"categories_names":{"7":{"name":"BARRANQUILLA","link":"https:\/\/www.noticias247.com.co\/news\/category\/barranquilla\/"}},"tags_names":[],"comments_number":"0","_links":{"self":[{"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/posts\/14740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/comments?post=14740"}],"version-history":[{"count":1,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/posts\/14740\/revisions"}],"predecessor-version":[{"id":14742,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/posts\/14740\/revisions\/14742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/media\/14741"}],"wp:attachment":[{"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/media?parent=14740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/categories?post=14740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticias247.com.co\/news\/wp-json\/wp\/v2\/tags?post=14740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}